{"id":1700,"date":"2017-11-21T10:00:14","date_gmt":"2017-11-21T09:00:14","guid":{"rendered":"https:\/\/preblogs.deusto.es\/aprender-ensenar\/?p=1700"},"modified":"2020-01-23T12:16:04","modified_gmt":"2020-01-23T11:16:04","slug":"docencia-online-una-gran-experiencia-de-aprendizaje","status":"publish","type":"post","link":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/","title":{"rendered":"Docencia online, una gran experiencia de aprendizaje"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Cuando me invitaron a escribir mi experiencia como profesora online me pareci\u00f3 una excelente oportunidad para pararme y reflexionar cr\u00edticamente sobre mi manera de hacer como docente en una universidad virtual con la que colaboro desde el a\u00f1o 2005. Me considero una persona muy afortunada por haber podido ir \u201cviviendo\u201d los avances en materia de formaci\u00f3n en los entornos virtuales, e ir comprobando d\u00eda a d\u00eda que la coexistencia entre lo virtual y lo presencial es posible. Al hablar de docencia online en diferentes foros y entornos acad\u00e9micos, se constata la relevancia que est\u00e1n teniendo tem\u00e1ticas como la irrupci\u00f3n de las TIC, el empuje del mercado, la econom\u00eda, las nuevas generaciones, los mal llamados \u201cnativos digitales\u201d, etc. y su impacto en el avance de la formaci\u00f3n online.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-1710\" src=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15-300x148.jpg\" alt=\"wo-15\" width=\"300\" height=\"148\" srcset=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15-300x148.jpg 300w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15-1024x505.jpg 1024w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15-960x473.jpg 960w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/span><\/p>\n<p><span style=\"font-weight: 400;\">El rol del docente en la universidad presencial cambia derivado del proceso de Bolonia, nuestro papel va dirigido m\u00e1s a tutorizar y acompa\u00f1ar al estudiante en el proceso de aprendizaje, que a transmitir solo conocimiento. Este rol, precisamente, cobra especial relevancia en un entorno virtual, en el que los estudiantes disponen de toda la informaci\u00f3n y el profesor ayuda, acompa\u00f1a, motiva e impulsa el aprendizaje, el estudiante es el verdadero protagonista de la docencia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre las competencias que requiere el entorno virtual destaco la capacidad de empatizar con los estudiantes, motivando su aprendizaje. El \u201csentirse acompa\u00f1ado\u201d correlaciona directamente con los resultados que se obtienen. Hay muchas formas de acompa\u00f1ar en el aprendizaje online, desde preparar unos excelentes materiales docentes en diferentes formatos (documentos, videos\u2026), hasta trabajar muy bien los mensajes que se trasladan. Si la comunicaci\u00f3n interpersonal es clave en cualquier situaci\u00f3n, cobra especial relevancia en el entorno virtual, de hecho, la primera formaci\u00f3n que recib\u00ed fue un curso sobre \u201cc\u00f3mo redactar mensajes\u201d y \u201cc\u00f3mo dar feedback en el entorno virtual\u201d, aprend\u00ed mucho, y gracias a ello mi docencia es m\u00e1s gratificante y as\u00ed lo percibo de mis estudiantes virtuales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, suelen preguntarme si es posible el trabajo en equipo en un entorno online. No solo es posible, sino que el trabajo con equipos virtuales es una necesidad, es una de las competencias que m\u00e1s se demanda en el mundo globalizado en que estamos. <span style=\"font-weight: 400;\">A modo de ejemplo, desde hace a\u00f1os trabajo con un equipo de docentes de diferentes partes del mundo con resultados excelentes en docencia e investigaci\u00f3n sin que nunca nos hayamos visto \u201cen persona\u201d.<\/span><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-1703\" src=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-content\/uploads\/sites\/7\/2017\/11\/net-1989138_1920-300x200.png\" alt=\"ne-19\" width=\"300\" height=\"200\" srcset=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/net-1989138_1920-300x200.png 300w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/net-1989138_1920-1024x683.png 1024w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/net-1989138_1920-960x640.png 960w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/net-1989138_1920-480x320.png 480w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/net-1989138_1920-380x255.png 380w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/net-1989138_1920.png 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, hay exigencias que demanda el entorno virtual, por ejemplo, unos m\u00ednimos en materia de tecnolog\u00eda, uso de plataforma correspondiente y tambi\u00e9n en cuanto al dise\u00f1o y creaci\u00f3n de nuevos materiales online. Para todo ello contar con un apoyo institucional ha sido fundamental.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Recientemente un compa\u00f1ero de Deusto que acaba de participar en un curso online me comentaba que \u201cs<\/span><i><span style=\"font-weight: 400;\">i lo pruebas, te acaba gustando y quieres seguir aprendiendo<\/span><\/i><span style=\"font-weight: 400;\">\u2026\u201d, reconociendo el esfuerzo que ha supuesto, pero afirmando que merece la pena y que se puede aprender. \u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tengo la suerte de impartir docencia online y presencial, y no ser\u00eda capaz de valorar qu\u00e9 tipo de ense\u00f1anza me supone m\u00e1s tiempo de preparaci\u00f3n, si queremos ser profesores excelentes en ambos entornos, dedicaremos el tiempo que estimemos necesario para conseguir resultados de calidad. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estoy muy agradecida al poder compaginar los dos entornos, que insisto, no son excluyentes, sino todo lo contrario. Voy ya para m\u00e1s de una d\u00e9cada en la docencia virtual y, como reza el t\u00edtulo del post, la curva de aprendizaje no para de crecer. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando me invitaron a escribir mi experiencia como profesora online me pareci\u00f3 una excelente oportunidad para pararme y reflexionar cr\u00edticamente sobre mi manera de hacer como docente en una universidad virtual con la que colaboro desde el a\u00f1o 2005. Me&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/\">Seguir leyendo &rarr;<\/a><\/p>\n","protected":false},"author":191,"featured_media":1710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[134,130,131,184,53,185,124,141],"class_list":["post-1700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-aprendizaje","tag-e-learning","tag-ecampus","tag-ensenanza-online","tag-formacion-online","tag-online-learning","tag-presencialidad-virtual","tag-universidad-de-deusto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Docencia online, una gran experiencia de aprendizaje - Aprender para ense\u00f1ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Docencia online, una gran experiencia de aprendizaje - Aprender para ense\u00f1ar\" \/>\n<meta property=\"og:description\" content=\"Cuando me invitaron a escribir mi experiencia como profesora online me pareci\u00f3 una excelente oportunidad para pararme y reflexionar cr\u00edticamente sobre mi manera de hacer como docente en una universidad virtual con la que colaboro desde el a\u00f1o 2005. Me... Seguir leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender para ense\u00f1ar\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-21T09:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-23T11:16:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"946\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mila Perez Gonzalez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mila Perez Gonzalez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/\"},\"author\":{\"name\":\"Mila Perez Gonzalez\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/fe4c7e6ee9d6020978e777cd2d827853\"},\"headline\":\"Docencia online, una gran experiencia de aprendizaje\",\"datePublished\":\"2017-11-21T09:00:14+00:00\",\"dateModified\":\"2020-01-23T11:16:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/\"},\"wordCount\":618,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/wo-15.jpg\",\"keywords\":[\"Aprendizaje\",\"e-learning\",\"eCampus\",\"ense\u00f1anza online\",\"formaci\u00f3n online\",\"online learning\",\"presencialidad virtual\",\"Universidad de Deusto\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/\",\"name\":\"Docencia online, una gran experiencia de aprendizaje - Aprender para ense\u00f1ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/wo-15.jpg\",\"datePublished\":\"2017-11-21T09:00:14+00:00\",\"dateModified\":\"2020-01-23T11:16:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/fe4c7e6ee9d6020978e777cd2d827853\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/wo-15.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/wo-15.jpg\",\"width\":1920,\"height\":946},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/docencia-online-una-gran-experiencia-de-aprendizaje\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docencia online, una gran experiencia de aprendizaje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\",\"name\":\"Aprender para ense\u00f1ar\",\"description\":\"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/fe4c7e6ee9d6020978e777cd2d827853\",\"name\":\"Mila Perez Gonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/mil-150x150.jpg\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/mil-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/11\\\/mil-150x150.jpg\",\"caption\":\"Mila Perez Gonzalez\"},\"description\":\"Profesora titular Deusto Business School, Universidad de Deusto Profesora colaboradora Universit\u00e1 Oberta Catalunya (UOC)\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/author\\\/mila-perez-gonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Docencia online, una gran experiencia de aprendizaje - Aprender para ense\u00f1ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/","og_locale":"es_ES","og_type":"article","og_title":"Docencia online, una gran experiencia de aprendizaje - Aprender para ense\u00f1ar","og_description":"Cuando me invitaron a escribir mi experiencia como profesora online me pareci\u00f3 una excelente oportunidad para pararme y reflexionar cr\u00edticamente sobre mi manera de hacer como docente en una universidad virtual con la que colaboro desde el a\u00f1o 2005. Me... Seguir leyendo &rarr;","og_url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/","og_site_name":"Aprender para ense\u00f1ar","article_published_time":"2017-11-21T09:00:14+00:00","article_modified_time":"2020-01-23T11:16:04+00:00","og_image":[{"width":1920,"height":946,"url":"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15.jpg","type":"image\/jpeg"}],"author":"Mila Perez Gonzalez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mila Perez Gonzalez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/#article","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/"},"author":{"name":"Mila Perez Gonzalez","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/fe4c7e6ee9d6020978e777cd2d827853"},"headline":"Docencia online, una gran experiencia de aprendizaje","datePublished":"2017-11-21T09:00:14+00:00","dateModified":"2020-01-23T11:16:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/"},"wordCount":618,"commentCount":0,"image":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15.jpg","keywords":["Aprendizaje","e-learning","eCampus","ense\u00f1anza online","formaci\u00f3n online","online learning","presencialidad virtual","Universidad de Deusto"],"articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/","name":"Docencia online, una gran experiencia de aprendizaje - Aprender para ense\u00f1ar","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/#primaryimage"},"image":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15.jpg","datePublished":"2017-11-21T09:00:14+00:00","dateModified":"2020-01-23T11:16:04+00:00","author":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/fe4c7e6ee9d6020978e777cd2d827853"},"breadcrumb":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/#primaryimage","url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15.jpg","contentUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/wo-15.jpg","width":1920,"height":946},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/docencia-online-una-gran-experiencia-de-aprendizaje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.deusto.es\/aprender-ensenar\/"},{"@type":"ListItem","position":2,"name":"Docencia online, una gran experiencia de aprendizaje"}]},{"@type":"WebSite","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/","name":"Aprender para ense\u00f1ar","description":"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.deusto.es\/aprender-ensenar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/fe4c7e6ee9d6020978e777cd2d827853","name":"Mila Perez Gonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/mil-150x150.jpg","url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/mil-150x150.jpg","contentUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/11\/mil-150x150.jpg","caption":"Mila Perez Gonzalez"},"description":"Profesora titular Deusto Business School, Universidad de Deusto Profesora colaboradora Universit\u00e1 Oberta Catalunya (UOC)","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/author\/mila-perez-gonzalez\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/1700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/comments?post=1700"}],"version-history":[{"count":25,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/1700\/revisions"}],"predecessor-version":[{"id":3509,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/1700\/revisions\/3509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/media\/1710"}],"wp:attachment":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/media?parent=1700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/categories?post=1700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/tags?post=1700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}