{"id":2230,"date":"2018-11-06T10:00:33","date_gmt":"2018-11-06T09:00:33","guid":{"rendered":"https:\/\/preblogs.deusto.es\/aprender-ensenar\/?p=2230"},"modified":"2020-01-23T12:17:08","modified_gmt":"2020-01-23T11:17:08","slug":"la-pizarra-ese-clasico-popular","status":"publish","type":"post","link":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/","title":{"rendered":"La pizarra, ese cl\u00e1sico popular"},"content":{"rendered":"<div id=\"attachment_2243\" style=\"width: 285px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-content\/uploads\/sites\/7\/2018\/11\/Un-cla\u0301sico-popular.png\" target=\"_blank\" rel=\"noopener noreferrer\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-2243\" class=\"wp-image-2243 \" src=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-content\/uploads\/sites\/7\/2018\/11\/Un-cla\u0301sico-popular-200x300.png\" alt=\"\" width=\"275\" height=\"413\" srcset=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/Un-cla\u0301sico-popular-200x300.png 200w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/Un-cla\u0301sico-popular-768x1152.png 768w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/Un-cla\u0301sico-popular-683x1024.png 683w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/Un-cla\u0301sico-popular-640x960.png 640w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/Un-cla\u0301sico-popular.png 800w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/><\/a><p id=\"caption-attachment-2243\" class=\"wp-caption-text\">Haz clic para agrandar la imagen<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left; margin: 0cm 3.35pt 5.45pt -.15pt;\"><span style=\"font-family: Arial;\">Cuando vemos reproducida una fotograf\u00eda o un dibujo de una pizarra en un documento cualquiera inmediatamente intuimos que vamos a leer algo sobre la escuela, la ense\u00f1anza,\u00a0<\/span><span style=\"font-family: Arial;\">el aprendizaje.\u00a0 <\/span><\/p>\n<p style=\"text-align: left; margin: 0cm 3.35pt 5.45pt -.15pt;\"><span style=\"font-family: Arial;\">El uso de la pizarra se ha extendido tanto desde que comenz\u00f3 a utilizarse como medio de apoyo a la explicaci\u00f3n de los docentes que se ha convertido en un s\u00edmbolo ic\u00f3nico del aula y est\u00e1 presente en la mayor\u00eda de ellas, ya sea la moderna pizarra digital interactiva, la blanca para escribir con rotuladores o la pizarra cl\u00e1sica para tiza.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: Arial;\">A continuaci\u00f3n os presentamos una posibilidad de utilizar este medio conocido y habitual en grabaciones de v\u00eddeo de nuestras explicaciones.<\/span><\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/hB2ykwtqW-g\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Infograf\u00eda realizada con <a href=\"https:\/\/www.canva.com\/\">Canva<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Cuando vemos reproducida una fotograf\u00eda o un dibujo de una pizarra en un documento cualquiera inmediatamente intuimos que vamos a leer algo sobre la escuela, la ense\u00f1anza,\u00a0el aprendizaje.\u00a0 El uso de la pizarra se ha&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/\">Seguir leyendo &rarr;<\/a><\/p>\n","protected":false},"author":159,"featured_media":2279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[378,130,131,379,376,377,223],"class_list":["post-2230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-cristal","tag-e-learning","tag-ecampus","tag-medio-didactico","tag-online","tag-pizarra","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La pizarra, ese cl\u00e1sico popular - Aprender para ense\u00f1ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pizarra, ese cl\u00e1sico popular - Aprender para ense\u00f1ar\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Cuando vemos reproducida una fotograf\u00eda o un dibujo de una pizarra en un documento cualquiera inmediatamente intuimos que vamos a leer algo sobre la escuela, la ense\u00f1anza,\u00a0el aprendizaje.\u00a0 El uso de la pizarra se ha... Seguir leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender para ense\u00f1ar\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-06T09:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-23T11:17:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/7\/2018\/11\/An_crst120.png\" \/>\n\t<meta property=\"og:image:width\" content=\"952\" \/>\n\t<meta property=\"og:image:height\" content=\"863\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Angela Garc\u00eda P\u00e9rez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Angela Garc\u00eda P\u00e9rez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/\"},\"author\":{\"name\":\"Angela Garc\u00eda P\u00e9rez\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/e706caf93aa6748c55ad3d8adac06b53\"},\"headline\":\"La pizarra, ese cl\u00e1sico popular\",\"datePublished\":\"2018-11-06T09:00:33+00:00\",\"dateModified\":\"2020-01-23T11:17:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/\"},\"wordCount\":156,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/11\\\/An_crst120.png\",\"keywords\":[\"cristal\",\"e-learning\",\"eCampus\",\"medio did\u00e1ctico\",\"online\",\"pizarra\",\"v\u00eddeo\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/\",\"name\":\"La pizarra, ese cl\u00e1sico popular - Aprender para ense\u00f1ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/11\\\/An_crst120.png\",\"datePublished\":\"2018-11-06T09:00:33+00:00\",\"dateModified\":\"2020-01-23T11:17:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/e706caf93aa6748c55ad3d8adac06b53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/11\\\/An_crst120.png\",\"contentUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/11\\\/An_crst120.png\",\"width\":952,\"height\":863},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/la-pizarra-ese-clasico-popular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La pizarra, ese cl\u00e1sico popular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\",\"name\":\"Aprender para ense\u00f1ar\",\"description\":\"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/e706caf93aa6748c55ad3d8adac06b53\",\"name\":\"Angela Garc\u00eda P\u00e9rez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/05\\\/angela_garcia_foto-1-150x150.jpg\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/05\\\/angela_garcia_foto-1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/05\\\/angela_garcia_foto-1-150x150.jpg\",\"caption\":\"Angela Garc\u00eda P\u00e9rez\"},\"description\":\"Asesora en Unidad Deusto Online. Doctora en Educaci\u00f3n. Docente en Universidad de Deusto. Voluntaria en Zerbikas.\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/author\\\/angela-perez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La pizarra, ese cl\u00e1sico popular - Aprender para ense\u00f1ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/","og_locale":"es_ES","og_type":"article","og_title":"La pizarra, ese cl\u00e1sico popular - Aprender para ense\u00f1ar","og_description":"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Cuando vemos reproducida una fotograf\u00eda o un dibujo de una pizarra en un documento cualquiera inmediatamente intuimos que vamos a leer algo sobre la escuela, la ense\u00f1anza,\u00a0el aprendizaje.\u00a0 El uso de la pizarra se ha... Seguir leyendo &rarr;","og_url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/","og_site_name":"Aprender para ense\u00f1ar","article_published_time":"2018-11-06T09:00:33+00:00","article_modified_time":"2020-01-23T11:17:08+00:00","og_image":[{"width":952,"height":863,"url":"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/7\/2018\/11\/An_crst120.png","type":"image\/png"}],"author":"Angela Garc\u00eda P\u00e9rez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Angela Garc\u00eda P\u00e9rez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/#article","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/"},"author":{"name":"Angela Garc\u00eda P\u00e9rez","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/e706caf93aa6748c55ad3d8adac06b53"},"headline":"La pizarra, ese cl\u00e1sico popular","datePublished":"2018-11-06T09:00:33+00:00","dateModified":"2020-01-23T11:17:08+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/"},"wordCount":156,"commentCount":0,"image":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/An_crst120.png","keywords":["cristal","e-learning","eCampus","medio did\u00e1ctico","online","pizarra","v\u00eddeo"],"articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/","name":"La pizarra, ese cl\u00e1sico popular - Aprender para ense\u00f1ar","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/#primaryimage"},"image":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/An_crst120.png","datePublished":"2018-11-06T09:00:33+00:00","dateModified":"2020-01-23T11:17:08+00:00","author":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/e706caf93aa6748c55ad3d8adac06b53"},"breadcrumb":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/#primaryimage","url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/An_crst120.png","contentUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2018\/11\/An_crst120.png","width":952,"height":863},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/la-pizarra-ese-clasico-popular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.deusto.es\/aprender-ensenar\/"},{"@type":"ListItem","position":2,"name":"La pizarra, ese cl\u00e1sico popular"}]},{"@type":"WebSite","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/","name":"Aprender para ense\u00f1ar","description":"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.deusto.es\/aprender-ensenar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/e706caf93aa6748c55ad3d8adac06b53","name":"Angela Garc\u00eda P\u00e9rez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/05\/angela_garcia_foto-1-150x150.jpg","url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/05\/angela_garcia_foto-1-150x150.jpg","contentUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2017\/05\/angela_garcia_foto-1-150x150.jpg","caption":"Angela Garc\u00eda P\u00e9rez"},"description":"Asesora en Unidad Deusto Online. Doctora en Educaci\u00f3n. Docente en Universidad de Deusto. Voluntaria en Zerbikas.","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/author\/angela-perez\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/2230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/comments?post=2230"}],"version-history":[{"count":50,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/2230\/revisions"}],"predecessor-version":[{"id":3589,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/2230\/revisions\/3589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/media\/2279"}],"wp:attachment":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/media?parent=2230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/categories?post=2230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/tags?post=2230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}