{"id":5633,"date":"2023-11-14T10:00:00","date_gmt":"2023-11-14T09:00:00","guid":{"rendered":"https:\/\/preblogs.deusto.es\/aprender-ensenar\/?p=5633"},"modified":"2023-11-12T22:44:57","modified_gmt":"2023-11-12T21:44:57","slug":"evaluando-de-mil-maneras","status":"publish","type":"post","link":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/","title":{"rendered":"Evaluando de mil maneras"},"content":{"rendered":"\n<p>Hoy compartimos con todas vosotras un post sobre <strong>evaluaci\u00f3n <\/strong>que, si bien es de una web dirigida principalmente a maestros y maestras, como docentes seguro que nos da muchas ideas a la hora de dise\u00f1ar la evaluaci\u00f3n por competencias de nuestras asignaturas. En el post encontrar\u00e9is <strong>m\u00e1s de 40 formas, productos y metodolog\u00edas diferentes para evaluar<\/strong>, de las cuales, seguro que muchas conoc\u00e9is, pero nos vendr\u00e1n muy bien para recordar y para aprender y\/o considerar otras maneras distintas a las que normalmente utilizamos para evaluar.<\/p>\n\n\n\n<p>Es importante que tengamos en cuenta que la evaluaci\u00f3n siempre se planificar\u00e1 en funci\u00f3n de las competencias y los objetivos formulados, pero tambi\u00e9n es necesario no olvidar que hemos de ser diversos y variar nuestra manera de evaluar para poder llegar (y hacer felices) a todo el alumnado.<\/p>\n\n\n\n<p><a href=\"https:\/\/webdelmaestrocmf.com\/portal\/25-maneras-diferentes-de-evaluar-a-tus-alumnos\/\">Aqu\u00ed<\/a> os dejamos el post.<\/p>\n\n\n\n<p>Esperamos que os sea de utilidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy compartimos con todas vosotras un post sobre evaluaci\u00f3n que, si bien es de una web dirigida principalmente a maestros y maestras, como docentes seguro que nos da muchas ideas a la hora de dise\u00f1ar la evaluaci\u00f3n por competencias de&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/\">Seguir leyendo &rarr;<\/a><\/p>\n","protected":false},"author":477,"featured_media":5634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[868,46],"tags":[333,869,109],"class_list":["post-5633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evaluacion","category-formacion","tag-evaluacion","tag-evaluacion-por-competencias","tag-formacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evaluando de mil maneras - Aprender para ense\u00f1ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evaluando de mil maneras - Aprender para ense\u00f1ar\" \/>\n<meta property=\"og:description\" content=\"Hoy compartimos con todas vosotras un post sobre evaluaci\u00f3n que, si bien es de una web dirigida principalmente a maestros y maestras, como docentes seguro que nos da muchas ideas a la hora de dise\u00f1ar la evaluaci\u00f3n por competencias de... Seguir leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender para ense\u00f1ar\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T09:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/7\/2023\/11\/health-2382316_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arantza Arruti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arantza Arruti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/\"},\"author\":{\"name\":\"Arantza Arruti\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/8a0212a9731cd746870775be37e340f2\"},\"headline\":\"Evaluando de mil maneras\",\"datePublished\":\"2023-11-14T09:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/\"},\"wordCount\":159,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/health-2382316_1280.jpg\",\"keywords\":[\"evaluaci\u00f3n\",\"evaluaci\u00f3n por competencias\",\"formaci\u00f3n\"],\"articleSection\":[\"Evaluaci\u00f3n\",\"Formaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/\",\"name\":\"Evaluando de mil maneras - Aprender para ense\u00f1ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/health-2382316_1280.jpg\",\"datePublished\":\"2023-11-14T09:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/8a0212a9731cd746870775be37e340f2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/health-2382316_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/11\\\/health-2382316_1280.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/evaluando-de-mil-maneras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evaluando de mil maneras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\",\"name\":\"Aprender para ense\u00f1ar\",\"description\":\"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/8a0212a9731cd746870775be37e340f2\",\"name\":\"Arantza Arruti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/07\\\/Foto-Aran-recortada-150x150.jpg\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/07\\\/Foto-Aran-recortada-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/07\\\/Foto-Aran-recortada-150x150.jpg\",\"caption\":\"Arantza Arruti\"},\"description\":\"Profesora de la Facultad de Educaci\u00f3n y Deporte, miembro de la Unidad de Innovaci\u00f3n Docente y del equipo de investigaci\u00f3n eDucaR -Deusto Education Research (https:\\\/\\\/blogs.deusto.es\\\/educar\\\/) de la Universidad de Deusto. Apasionada del emprendimiento y la persona emprendedora. Es editora del blog https:\\\/\\\/www.arantzaarruti.com\\\/ y coordinadora del blog Aprender para Ense\u00f1ar (https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/). Puedes contactar con ella a trav\u00e9s de su mail: aarruti@deusto.es\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/author\\\/aarrutideusto-es\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evaluando de mil maneras - Aprender para ense\u00f1ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/","og_locale":"es_ES","og_type":"article","og_title":"Evaluando de mil maneras - Aprender para ense\u00f1ar","og_description":"Hoy compartimos con todas vosotras un post sobre evaluaci\u00f3n que, si bien es de una web dirigida principalmente a maestros y maestras, como docentes seguro que nos da muchas ideas a la hora de dise\u00f1ar la evaluaci\u00f3n por competencias de... Seguir leyendo &rarr;","og_url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/","og_site_name":"Aprender para ense\u00f1ar","article_published_time":"2023-11-14T09:00:00+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/7\/2023\/11\/health-2382316_1280.jpg","type":"image\/jpeg"}],"author":"Arantza Arruti","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arantza Arruti","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/#article","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/"},"author":{"name":"Arantza Arruti","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/8a0212a9731cd746870775be37e340f2"},"headline":"Evaluando de mil maneras","datePublished":"2023-11-14T09:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/"},"wordCount":159,"commentCount":0,"image":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2023\/11\/health-2382316_1280.jpg","keywords":["evaluaci\u00f3n","evaluaci\u00f3n por competencias","formaci\u00f3n"],"articleSection":["Evaluaci\u00f3n","Formaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/","name":"Evaluando de mil maneras - Aprender para ense\u00f1ar","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/#primaryimage"},"image":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2023\/11\/health-2382316_1280.jpg","datePublished":"2023-11-14T09:00:00+00:00","author":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/8a0212a9731cd746870775be37e340f2"},"breadcrumb":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/#primaryimage","url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2023\/11\/health-2382316_1280.jpg","contentUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2023\/11\/health-2382316_1280.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/evaluando-de-mil-maneras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.deusto.es\/aprender-ensenar\/"},{"@type":"ListItem","position":2,"name":"Evaluando de mil maneras"}]},{"@type":"WebSite","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/","name":"Aprender para ense\u00f1ar","description":"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.deusto.es\/aprender-ensenar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/8a0212a9731cd746870775be37e340f2","name":"Arantza Arruti","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2019\/07\/Foto-Aran-recortada-150x150.jpg","url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2019\/07\/Foto-Aran-recortada-150x150.jpg","contentUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2019\/07\/Foto-Aran-recortada-150x150.jpg","caption":"Arantza Arruti"},"description":"Profesora de la Facultad de Educaci\u00f3n y Deporte, miembro de la Unidad de Innovaci\u00f3n Docente y del equipo de investigaci\u00f3n eDucaR -Deusto Education Research (https:\/\/blogs.deusto.es\/educar\/) de la Universidad de Deusto. Apasionada del emprendimiento y la persona emprendedora. Es editora del blog https:\/\/www.arantzaarruti.com\/ y coordinadora del blog Aprender para Ense\u00f1ar (https:\/\/blogs.deusto.es\/aprender-ensenar\/). Puedes contactar con ella a trav\u00e9s de su mail: aarruti@deusto.es","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/author\/aarrutideusto-es\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/5633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/users\/477"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/comments?post=5633"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/5633\/revisions"}],"predecessor-version":[{"id":5636,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/5633\/revisions\/5636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/media\/5634"}],"wp:attachment":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/media?parent=5633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/categories?post=5633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/tags?post=5633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}