{"id":640,"date":"2016-10-04T11:46:25","date_gmt":"2016-10-04T09:46:25","guid":{"rendered":"https:\/\/preblogs.deusto.es\/aprender-ensenar\/?p=640"},"modified":"2020-01-23T12:14:34","modified_gmt":"2020-01-23T11:14:34","slug":"contrasenas-unicas-y-seguras","status":"publish","type":"post","link":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/","title":{"rendered":"Contrase\u00f1as \u00fanicas y seguras"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Seguramente, todos y cada uno de vosotros hay\u00e1is vivido en m\u00e1s de una ocasi\u00f3n la siguiente situaci\u00f3n: \u201cintroduzca una nueva contrase\u00f1a\u201d. Esto es, vamos a crear una cuenta de un servicio y en ese momento se nos solicita la introducci\u00f3n de una contrase\u00f1a. En ese instante, lo primero que suele pasar por nuestra cabeza suele ser: \u201c\u00bfc\u00f3mo voy a acordarme de la nueva contrase\u00f1a?\u201d lo que solemos solucionar por \u201cla v\u00eda r\u00e1pida\u201d: usar la contrase\u00f1a de siempre :-). Contrase\u00f1a que, muy probablemente sea poco segura y que cumpla alguno de los siguientes criterios: poseer mi nombre o el de alg\u00fan ser querido, contener fechas relevantes, el nombre de alguna mascota, secuencias de caracteres simples (1234, 34343434&#8230;), \u2026 por supuesto, no sois los \u00fanicos y para que pod\u00e1is comprobarlo, os dejo <\/span><a href=\"http:\/\/www.t13.cl\/noticia\/tendencias\/tecnologia\/estas-fueron-25-contrasenas-mas-utilizadas-2015\"><span style=\"font-weight: 400;\">aqu\u00ed<\/span><\/a><span style=\"font-weight: 400;\"> un link a las contrase\u00f1as m\u00e1s usadas a lo largo del pasado a\u00f1o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ahora una buena pregunta ser\u00eda, \u00bfpuedo crear contrase\u00f1as seguras, distintas y que pueda recordar? La respuesta es s\u00ed y, para ello, tan s\u00f3lo hay que emplear un par de sencillos trucos. En primer lugar, hemos de categorizar los sitios web que solemos visitar creando una tabla:<\/span><\/p>\n<p><a href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-content\/uploads\/sites\/7\/2016\/09\/tabla.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-641\" src=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-content\/uploads\/sites\/7\/2016\/09\/tabla.jpg\" alt=\"tabla\" width=\"562\" height=\"257\" srcset=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/09\/tabla.jpg 793w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/09\/tabla-300x137.jpg 300w\" sizes=\"(max-width: 562px) 100vw, 562px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En segundo lugar, hemos de pensar una frase de ocho palabras, la cual emplearemos como parte com\u00fan a todas nuestras contrase\u00f1as. Ejemplo: \u201cUn elefante se balanceaba sobre la tela de\u201d. Ahora lo que debemos hacer es seleccionar la primera letra de cada una de las palabras: <\/span><b>uesbsltd<\/b><span style=\"font-weight: 400;\">. Una vez hecho, deberemos cambiar alg\u00fan caracter por n\u00fameros, may\u00fasculas o caracteres especiales. Yo por ejemplo, voy a cambiar siempre la S por el s\u00edmbolo \u201c$\u201d y la L por \u201c1\u201d. De esta forma, obtengo <\/span><b>ue$b$1td <\/b><span style=\"font-weight: 400;\">\u00a0que ser\u00e1 la parte com\u00fan a todas mis contrase\u00f1as.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ahora imaginemos que quiero crear una contrase\u00f1a para mi cuenta Facebook, ya sabemos que tenemos una primera parte de la misma: <\/span><b>ue$b$1td <\/b><span style=\"font-weight: 400;\">y a \u00e9sta deberemos a\u00f1adir tres caracteres de la categor\u00eda (Ejemplo: Categor\u00eda = <\/span><b>Re<\/b><span style=\"font-weight: 400;\">des <\/span><b>S<\/b><span style=\"font-weight: 400;\">ociales. Escojo res) y aplicar las mismas normas de caracteres o s\u00edmbolos que a la anterior: <\/span><b>re$. <\/b><span style=\"font-weight: 400;\">De esta forma, mi contrase\u00f1a hasta el momento es: <\/span><b>ue$b$1tdre$<\/b><span style=\"font-weight: 400;\">. Por \u00faltimo, habr\u00e9 de a\u00f1adir tres caracteres para el sitio web (Ejemplo:sitio web: Facebook. Escojo: <\/span><b>fac<\/b><span style=\"font-weight: 400;\">) y aplicar las normas relativas a caracteres y s\u00edmbolos. De esta forma mi contrase\u00f1a final para facebook ser\u00eda: <\/span><b>ue$b$1tdre$fac<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si te resulta m\u00e1s sencillo, puedes pinchar <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=jJibnjiKr8I\"><span style=\"font-weight: 400;\">aqu\u00ed<\/span><\/a><span style=\"font-weight: 400;\"> para ver un brev\u00edsimo v\u00eddeo con el contenido de la explicaci\u00f3n.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguramente, todos y cada uno de vosotros hay\u00e1is vivido en m\u00e1s de una ocasi\u00f3n la siguiente situaci\u00f3n: \u201cintroduzca una nueva contrase\u00f1a\u201d. Esto es, vamos a crear una cuenta de un servicio y en ese momento se nos solicita la introducci\u00f3n&#8230; <a class=\"more-link\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/\">Seguir leyendo &rarr;<\/a><\/p>\n","protected":false},"author":170,"featured_media":645,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[126,127,125],"class_list":["post-640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-contrasenas","tag-metodo","tag-seguridad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contrase\u00f1as \u00fanicas y seguras - Aprender para ense\u00f1ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contrase\u00f1as \u00fanicas y seguras - Aprender para ense\u00f1ar\" \/>\n<meta property=\"og:description\" content=\"Seguramente, todos y cada uno de vosotros hay\u00e1is vivido en m\u00e1s de una ocasi\u00f3n la siguiente situaci\u00f3n: \u201cintroduzca una nueva contrase\u00f1a\u201d. Esto es, vamos a crear una cuenta de un servicio y en ese momento se nos solicita la introducci\u00f3n... Seguir leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender para ense\u00f1ar\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-04T09:46:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-23T11:14:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/7\/2016\/09\/laptop-868816_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1209\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Est\u00edbaliz Curiel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Est\u00edbaliz Curiel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/\"},\"author\":{\"name\":\"Est\u00edbaliz Curiel\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/3c9e9cceccae526d423778cf634e9e52\"},\"headline\":\"Contrase\u00f1as \u00fanicas y seguras\",\"datePublished\":\"2016-10-04T09:46:25+00:00\",\"dateModified\":\"2020-01-23T11:14:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/\"},\"wordCount\":454,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/laptop-868816_1920.jpg\",\"keywords\":[\"contrase\u00f1as\",\"m\u00e9todo\",\"seguridad\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/\",\"name\":\"Contrase\u00f1as \u00fanicas y seguras - Aprender para ense\u00f1ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/laptop-868816_1920.jpg\",\"datePublished\":\"2016-10-04T09:46:25+00:00\",\"dateModified\":\"2020-01-23T11:14:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/3c9e9cceccae526d423778cf634e9e52\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/laptop-868816_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/laptop-868816_1920.jpg\",\"width\":1920,\"height\":1209},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/contrasenas-unicas-y-seguras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contrase\u00f1as \u00fanicas y seguras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\",\"name\":\"Aprender para ense\u00f1ar\",\"description\":\"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#\\\/schema\\\/person\\\/3c9e9cceccae526d423778cf634e9e52\",\"name\":\"Est\u00edbaliz Curiel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/02\\\/Sin-t\u00edtulo-150x150.png\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/02\\\/Sin-t\u00edtulo-150x150.png\",\"contentUrl\":\"https:\\\/\\\/blogs.deusto.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/02\\\/Sin-t\u00edtulo-150x150.png\",\"caption\":\"Est\u00edbaliz Curiel\"},\"description\":\"Responsable \u00c1rea de Soporte a Usuarios perteneciente al Servicio Inform\u00e1tico de la Universidad de Deusto. Puedes acceder a nuestro espacio a trav\u00e9s de http:\\\/\\\/aulatic.deusto.es\\\/\",\"sameAs\":[\"http:\\\/\\\/aulatic.deusto.es\\\/\"],\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/author\\\/esti-curiel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contrase\u00f1as \u00fanicas y seguras - Aprender para ense\u00f1ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/","og_locale":"es_ES","og_type":"article","og_title":"Contrase\u00f1as \u00fanicas y seguras - Aprender para ense\u00f1ar","og_description":"Seguramente, todos y cada uno de vosotros hay\u00e1is vivido en m\u00e1s de una ocasi\u00f3n la siguiente situaci\u00f3n: \u201cintroduzca una nueva contrase\u00f1a\u201d. Esto es, vamos a crear una cuenta de un servicio y en ese momento se nos solicita la introducci\u00f3n... Seguir leyendo &rarr;","og_url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/","og_site_name":"Aprender para ense\u00f1ar","article_published_time":"2016-10-04T09:46:25+00:00","article_modified_time":"2020-01-23T11:14:34+00:00","og_image":[{"width":1920,"height":1209,"url":"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/7\/2016\/09\/laptop-868816_1920.jpg","type":"image\/jpeg"}],"author":"Est\u00edbaliz Curiel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Est\u00edbaliz Curiel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/#article","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/"},"author":{"name":"Est\u00edbaliz Curiel","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/3c9e9cceccae526d423778cf634e9e52"},"headline":"Contrase\u00f1as \u00fanicas y seguras","datePublished":"2016-10-04T09:46:25+00:00","dateModified":"2020-01-23T11:14:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/"},"wordCount":454,"commentCount":2,"image":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/09\/laptop-868816_1920.jpg","keywords":["contrase\u00f1as","m\u00e9todo","seguridad"],"articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/","name":"Contrase\u00f1as \u00fanicas y seguras - Aprender para ense\u00f1ar","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/#primaryimage"},"image":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/09\/laptop-868816_1920.jpg","datePublished":"2016-10-04T09:46:25+00:00","dateModified":"2020-01-23T11:14:34+00:00","author":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/3c9e9cceccae526d423778cf634e9e52"},"breadcrumb":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/#primaryimage","url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/09\/laptop-868816_1920.jpg","contentUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/09\/laptop-868816_1920.jpg","width":1920,"height":1209},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/contrasenas-unicas-y-seguras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.deusto.es\/aprender-ensenar\/"},{"@type":"ListItem","position":2,"name":"Contrase\u00f1as \u00fanicas y seguras"}]},{"@type":"WebSite","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/","name":"Aprender para ense\u00f1ar","description":"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.deusto.es\/aprender-ensenar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#\/schema\/person\/3c9e9cceccae526d423778cf634e9e52","name":"Est\u00edbaliz Curiel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/02\/Sin-t\u00edtulo-150x150.png","url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/02\/Sin-t\u00edtulo-150x150.png","contentUrl":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/7\/2016\/02\/Sin-t\u00edtulo-150x150.png","caption":"Est\u00edbaliz Curiel"},"description":"Responsable \u00c1rea de Soporte a Usuarios perteneciente al Servicio Inform\u00e1tico de la Universidad de Deusto. Puedes acceder a nuestro espacio a trav\u00e9s de http:\/\/aulatic.deusto.es\/","sameAs":["http:\/\/aulatic.deusto.es\/"],"url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/author\/esti-curiel\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/users\/170"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/comments?post=640"}],"version-history":[{"count":4,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/640\/revisions"}],"predecessor-version":[{"id":3329,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts\/640\/revisions\/3329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/media\/645"}],"wp:attachment":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/media?parent=640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/categories?post=640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/tags?post=640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}