{"id":824,"count":1,"description":"","link":"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/","name":"dafo","slug":"dafo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>dafo archivos - Aprender para ense\u00f1ar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dafo archivos - Aprender para ense\u00f1ar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/\" \/>\n<meta property=\"og:site_name\" content=\"Aprender para ense\u00f1ar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/tag\\\/dafo\\\/\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/tag\\\/dafo\\\/\",\"name\":\"dafo archivos - Aprender para ense\u00f1ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/tag\\\/dafo\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/tag\\\/dafo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"dafo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/#website\",\"url\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/\",\"name\":\"Aprender para ense\u00f1ar\",\"description\":\"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.deusto.es\\\/aprender-ensenar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"dafo archivos - Aprender para ense\u00f1ar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/","og_locale":"es_ES","og_type":"article","og_title":"dafo archivos - Aprender para ense\u00f1ar","og_url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/","og_site_name":"Aprender para ense\u00f1ar","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/","name":"dafo archivos - Aprender para ense\u00f1ar","isPartOf":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/tag\/dafo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.deusto.es\/aprender-ensenar\/"},{"@type":"ListItem","position":2,"name":"dafo"}]},{"@type":"WebSite","@id":"https:\/\/blogs.deusto.es\/aprender-ensenar\/#website","url":"https:\/\/blogs.deusto.es\/aprender-ensenar\/","name":"Aprender para ense\u00f1ar","description":"Innovaci\u00f3n docente, Formaci\u00f3n Online, Formaci\u00f3n Dual  y TIC en la Universidad de Deusto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.deusto.es\/aprender-ensenar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/tags\/824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.deusto.es\/aprender-ensenar\/wp-json\/wp\/v2\/posts?tags=824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}