{"id":21016,"date":"2026-02-28T08:33:32","date_gmt":"2026-02-28T07:33:32","guid":{"rendered":"https:\/\/blogs.deusto.es\/iedeusto\/?p=21016"},"modified":"2026-03-02T09:15:02","modified_gmt":"2026-03-02T08:15:02","slug":"organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes","status":"publish","type":"post","link":"https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/","title":{"rendered":"Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES"},"content":{"rendered":"\n<p>Desde que el pasado mes de octubre comenz\u00e1ramos a trabajar en red y nos reuni\u00e9ramos por primera vez el Grupo de Hom\u00f3logos de Emprendimiento de <a href=\"https:\/\/unijes.net\/\" title=\"\">UNIJES<\/a> &#8211; Red de universidades y centros de educaci\u00f3n superior de la Compa\u00f1\u00eda de Jes\u00fas en Espa\u00f1a, formado por las personas responsables de emprendimiento de la <a href=\"https:\/\/www.google.com\/aclk?sa=L&amp;pf=1&amp;ai=DChsSEwi5rvy_4oCTAxWxkoMHHekRKBAYACICCAEQABoCZWY&amp;co=1&amp;ase=2&amp;gclid=CjwKCAiAh5XNBhAAEiwA_Bu8FeNUerisDFArAhdTI6qnGrundKwyNfjO-VLR9oILPaKC6CB9U2AtQhoCuuYQAvD_BwE&amp;cce=2&amp;category=acrcp_v1_32&amp;sig=AOD64_3PfB6htIxNqU1WvNtkGRDLIonv3A&amp;q&amp;nis=4&amp;adurl=https:\/\/www.deusto.es\/es\/inicio\/estudia\/estudios\/master-universitario\/automatizacion-electronica-y-control-industrial?utm_source%3Dgoogle%26utm_medium%3Dcpc%26utm_campaign%3D23503065039%26gad_source%3D1%26gad_campaignid%3D23508199832%26gbraid%3D0AAAAADeeHPno_atE567g9o7EsU_qLQSmH%26gclid%3DCjwKCAiAh5XNBhAAEiwA_Bu8FeNUerisDFArAhdTI6qnGrundKwyNfjO-VLR9oILPaKC6CB9U2AtQhoCuuYQAvD_BwE&amp;ved=2ahUKEwiauve_4oCTAxUXxQIHHWJRGfQQ0Qx6BAgUEAE\" title=\"\">Universidad de Deusto<\/a>, la <a href=\"https:\/\/www.uloyola.es\/\" title=\"\">Universidad Loyola<\/a>, la <a href=\"https:\/\/www.comillas.edu\/\" title=\"\">Universidad Pontificia Comillas<\/a> y <a href=\"https:\/\/iqs.edu\/\" title=\"\">IQS (Institut Qu\u00edmic de Sarri\u00e0) <\/a>&#8211; Universidad Ramon Llull, el compromiso compartido por avanzar juntas no ha dejado de crecer.<\/p>\n\n\n\n<p>Como resultado de ese impulso colectivo, los d\u00edas 24 y 25 de febrero hemos organizado una primera formaci\u00f3n en Inteligencia Artificial Generativa aplicada al emprendimiento, una iniciativa que supone solo el inicio de muchas otras acciones que ya tenemos entre manos para seguir fortaleciendo el ecosistema emprendedor desde nuestras universidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una mirada pr\u00e1ctica a la IA generativa<\/h3>\n\n\n\n<p>La formaci\u00f3n cont\u00f3 con <a href=\"https:\/\/es.linkedin.com\/in\/martairaola\" title=\"\">Marta Iraola<\/a> como ponente, colaboradora habitual de <a href=\"https:\/\/www.deusto.es\/es\/inicio\/somos-deusto\/centros-universitarios\/otros-centros\/deusto-emprende\" title=\"\">Deusto Emprende<\/a> y fundadora de <a href=\"https:\/\/donostik.com\/\" title=\"\">donosTIK<\/a>. A lo largo de dos sesiones online, Marta comparti\u00f3 una visi\u00f3n realista, cercana y muy aplicada de c\u00f3mo la Inteligencia Artificial Generativa puede integrarse de forma eficaz en proyectos emprendedores, sin perder de vista el criterio, la estrategia y las personas. Lejos de enfoques excesivamente t\u00e9cnicos o futuristas, la formaci\u00f3n puso el foco en el uso consciente y \u00fatil de la IA en el d\u00eda a d\u00eda, abordando preguntas muy concretas: <em>\u00bfPara qu\u00e9 me sirve?, \u00bfen qu\u00e9 procesos aporta valor?, \u00bfc\u00f3mo empiezo a usarla sin complicarme?<\/em><\/p>\n\n\n\n<p>Durante las sesiones, las personas participantes pudieron conocer casos y usos concretos de la IA generativa aplicables al contexto emprendedor, explorar herramientas pr\u00e1cticas tanto para el \u00e1mbito profesional como personal y reflexionar de manera conjunta sobre el impacto de la IA en la forma de trabajar, crear y tomar decisiones. Uno de los aspectos m\u00e1s enriquecedores de la formaci\u00f3n fue precisamente este intercambio entre las participantes: preguntas, ejemplos propios y reflexiones compartidas que pusieron de manifiesto que la Inteligencia Artificial ya no es una promesa futura, sino una herramienta presente que, bien utilizada, puede potenciar significativamente el acompa\u00f1amiento al emprendimiento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aprender en red para avanzar mejor<\/h3>\n\n\n\n<p>La experiencia fue positiva y dej\u00f3 en evidencia que seguir trabajando en red es clave para acompa\u00f1ar mejor a quienes emprenden desde nuestras universidades. La IA generativa abre nuevas oportunidades, pero tambi\u00e9n plantea retos \u00e9ticos, metodol\u00f3gicos y estrat\u00e9gicos que solo pueden abordarse desde el di\u00e1logo y el aprendizaje colectivo.<\/p>\n\n\n\n<p>Desde el Grupo de Hom\u00f3logos de Emprendimiento de UNIJES, seguimos apostando por espacios como este, que nos permiten compartir conocimiento, contrastar miradas y avanzar en red.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2026\/03\/Captura-de-pantalla-2026-02-24-a-las-5.12.11-p.-m.-1.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2026\/03\/Captura-de-pantalla-2026-02-24-a-las-5.12.11-p.-m.-1-1024x576.png\" alt=\"\" class=\"wp-image-21017\" srcset=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2026\/03\/Captura-de-pantalla-2026-02-24-a-las-5.12.11-p.-m.-1-1024x576.png 1024w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2026\/03\/Captura-de-pantalla-2026-02-24-a-las-5.12.11-p.-m.-1-300x169.png 300w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2026\/03\/Captura-de-pantalla-2026-02-24-a-las-5.12.11-p.-m.-1-768x432.png 768w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2026\/03\/Captura-de-pantalla-2026-02-24-a-las-5.12.11-p.-m.-1-1536x864.png 1536w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2026\/03\/Captura-de-pantalla-2026-02-24-a-las-5.12.11-p.-m.-1-2048x1152.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<p><span class='st_facebook_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='facebook'><\/span><span st_via='deustoDEC' st_username='deustoDEC' class='st_twitter_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='twitter'><\/span><span class='st_email_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='email'><\/span><span class='st_fblike_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='fblike'><\/span><span class='st_plusone_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='plusone'><\/span><span class='st_pinterest_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='pinterest'><\/span><span class='st_sharethis_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='sharethis'><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Desde que el pasado mes de octubre comenz\u00e1ramos a trabajar en red y nos reuni\u00e9ramos por primera vez el Grupo de Hom\u00f3logos de Emprendimiento de UNIJES &#8211; Red de universidades y centros de educaci\u00f3n superior de la Compa\u00f1\u00eda de Jes\u00fas en Espa\u00f1a, formado por las personas responsables de emprendimiento de la Universidad de Deusto, la [&hellip;]<\/p>\n<p><span class='st_facebook_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='facebook'><\/span><span st_via='deustoDEC' st_username='deustoDEC' class='st_twitter_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='twitter'><\/span><span class='st_email_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='email'><\/span><span class='st_fblike_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='fblike'><\/span><span class='st_plusone_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='plusone'><\/span><span class='st_pinterest_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='pinterest'><\/span><span class='st_sharethis_buttons' st_title='Organizamos una formaci\u00f3n en IA generativa para personas emprendedoras junto al Grupo de Hom\u00f3logos de Emprendimiento de UNIJES' st_url='https:\/\/blogs.deusto.es\/iedeusto\/organizamos-una-formacion-en-ia-generativa-para-personas-emprendedoras-junto-al-grupo-de-homologos-de-emprendimiento-de-unijes\/' displayText='sharethis'><\/span><\/p>","protected":false},"author":387,"featured_media":21018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-21016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2026\/03\/IA-Universidades-Jesuitas-24FEB.png","_links":{"self":[{"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/posts\/21016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/users\/387"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/comments?post=21016"}],"version-history":[{"count":2,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/posts\/21016\/revisions"}],"predecessor-version":[{"id":21021,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/posts\/21016\/revisions\/21021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/media\/21018"}],"wp:attachment":[{"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/media?parent=21016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/categories?post=21016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/tags?post=21016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}