{"id":3099,"date":"2014-04-29T12:02:06","date_gmt":"2014-04-29T10:02:06","guid":{"rendered":"https:\/\/preblogs.deusto.es\/iedeusto\/?p=3099"},"modified":"2018-07-09T12:24:06","modified_gmt":"2018-07-09T10:24:06","slug":"masterclass-sobre-google-glass","status":"publish","type":"post","link":"https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/","title":{"rendered":"Masterclass sobre Google Glass"},"content":{"rendered":"<p>El pasado mi\u00e9rcoles, 9 de abril, tuvo lugar una Masterclass en la Facultad de Ingenier\u00eda sobre las Google Glass.<\/p>\n<p>La charla estuvo enfocada a explicar el nuevo sistema operativo de las Google Glass para una selecto grupo de desarrolladores. Entre otras cosas, los t\u00e9cnicos de <a href=\"http:\/\/apps4glass.com\/\"><strong>apps4glass<\/strong> <\/a>explicaron que hay varios tipos de apps: apps y din\u00e1micas.<\/p>\n<p>Adem\u00e1s, al finalizar la Masterclass, los asistentes tuvieron el privilegio de probar las Google Glass.<\/p>\n<p><a href=\"https:\/\/blogs.deusto.es\/iedeusto\/wp-content\/uploads\/sites\/27\/2014\/04\/P1020647.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-3100\" src=\"https:\/\/blogs.deusto.es\/iedeusto\/wp-content\/uploads\/sites\/27\/2014\/04\/P1020647-1024x768.jpg\" alt=\"P1020647\" width=\"584\" height=\"438\" srcset=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2014\/04\/P1020647-1024x768.jpg 1024w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2014\/04\/P1020647-300x225.jpg 300w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2014\/04\/P1020647-400x300.jpg 400w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span class='st_facebook_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='facebook'><\/span><span st_via='deustoDEC' st_username='deustoDEC' class='st_twitter_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='twitter'><\/span><span class='st_email_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='email'><\/span><span class='st_fblike_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='fblike'><\/span><span class='st_plusone_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='plusone'><\/span><span class='st_pinterest_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='pinterest'><\/span><span class='st_sharethis_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='sharethis'><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado mi\u00e9rcoles, 9 de abril, tuvo lugar una Masterclass en la Facultad de Ingenier\u00eda sobre las Google Glass. La charla estuvo enfocada a explicar el nuevo sistema operativo de las Google Glass para una selecto grupo de desarrolladores. Entre otras cosas, los t\u00e9cnicos de apps4glass explicaron que hay varios tipos de apps: apps y [&hellip;]<\/p>\n<p><span class='st_facebook_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='facebook'><\/span><span st_via='deustoDEC' st_username='deustoDEC' class='st_twitter_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='twitter'><\/span><span class='st_email_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='email'><\/span><span class='st_fblike_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='fblike'><\/span><span class='st_plusone_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='plusone'><\/span><span class='st_pinterest_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='pinterest'><\/span><span class='st_sharethis_buttons' st_title='Masterclass sobre Google Glass' st_url='https:\/\/blogs.deusto.es\/iedeusto\/masterclass-sobre-google-glass\/' displayText='sharethis'><\/span><\/p>","protected":false},"author":387,"featured_media":3100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[40,10,8,1],"tags":[84],"class_list":["post-3099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deusto-entrepreneurship-centre","category-emprendedors","category-emprendimiento","category-sin-categoria","tag-google-glass"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/27\/2014\/04\/P1020647.jpg","_links":{"self":[{"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/posts\/3099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/users\/387"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/comments?post=3099"}],"version-history":[{"count":8,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/posts\/3099\/revisions"}],"predecessor-version":[{"id":7515,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/posts\/3099\/revisions\/7515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/media\/3100"}],"wp:attachment":[{"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/media?parent=3099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/categories?post=3099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deusto.es\/iedeusto\/wp-json\/wp\/v2\/tags?post=3099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}