{"id":2321,"date":"2023-03-03T11:52:07","date_gmt":"2023-03-03T11:52:07","guid":{"rendered":"https:\/\/preblogs.deusto.es\/viviendodeusto\/?p=2321"},"modified":"2023-03-14T16:33:27","modified_gmt":"2023-03-14T16:33:27","slug":"conoce-las-focus-room-la-ultima-revolucion-para-mejorar-tu-trabajo-y-estudio","status":"publish","type":"post","link":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/2023\/03\/03\/conoce-las-focus-room-la-ultima-revolucion-para-mejorar-tu-trabajo-y-estudio\/","title":{"rendered":"Conoce las &#8220;focus room&#8221;, la \u00faltima revoluci\u00f3n para mejorar tu trabajo y estudio"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"505\" src=\"https:\/\/blogs.deusto.es\/alumni\/wp-content\/uploads\/sites\/78\/2023\/03\/Noticia-web-4-1024x505.png\" alt=\"Pantalla de la focus room StudyTogetger.com\" class=\"wp-image-2325\" srcset=\"https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/78\/2023\/03\/Noticia-web-4-1024x505.png 1024w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/78\/2023\/03\/Noticia-web-4-300x148.png 300w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/78\/2023\/03\/Noticia-web-4-768x378.png 768w, https:\/\/blogs.deusto.es\/wp-content\/uploads\/sites\/78\/2023\/03\/Noticia-web-4.png 1380w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La concentraci\u00f3n es uno de los factores m\u00e1s importantes en la vida de las personas, sobretodo cuando uno es estudiante, ya que debe buscarse los medios para adquirir esta habilidad.\u00a0<\/p>\n\n\n\n<p>En este sentido, cada cual tiene diferentes formas o m\u00e9todos de concentraci\u00f3n seg\u00fan sus capacidades. Algunos se refugian en la soledad de sus habitaciones, sin sentir la presi\u00f3n de ning\u00fan otro factor, mientras que otros necesitan la compa\u00f1\u00eda de alguien o sentir que otra persona se encuentra en igualdad de condiciones para comenzar a estudiar. Es por ello por lo que buscan ambientes en las bibliotecas o cafeter\u00edas de estudio.<\/p>\n\n\n\n<p>De hecho, con el crecimiento del aprendizaje en remoto, las <em>focus room <\/em>(salas de concentraci\u00f3n) como <a href=\"https:\/\/www.studystream.live\/focus-room\">StudyStream.live<\/a> o <a href=\"https:\/\/www.studytogether.com\/\">StudyTogether.com<\/a>, se han hecho un hueco en los estudios de grupo o individuales online, ya que crean un ambiente de trabajo entre personas de todo el mundo mediante videollamadas. Son p\u00e1ginas web que impulsan tu concentraci\u00f3n y te ayudan a conocer gente nueva mientras logras tus metas u objetivos.&nbsp;<\/p>\n\n\n\n<p>\u00bfC\u00f3mo funcionan? Cuando eliges una <em>room <\/em>para conocer nuevos estudiantes, tienes la opci\u00f3n de seleccionar m\u00fasica ambiental y la c\u00e1mara encendida o apagada, o simplemente un chat de soporte y ayuda junto a otros estudiantes. A medida que vas navegando en cada sala, encontrar\u00e1s tambi\u00e9n diferentes aplicaciones para facilitar el estudio. Adem\u00e1s, si seleccionas un temporizador, podr\u00e1s calcular el tiempo para estudiar y establecer <em>breaks <\/em>(descansos) para no saturarte. En algunas webs, incluso, dispones de ayuda de tutores o sesiones de mindfulness, con colecciones de audios y v\u00eddeos de meditaci\u00f3n y ejercicios de respiraci\u00f3n que puedes llevar a cabo durante los descansos.&nbsp;<\/p>\n\n\n\n<p>Pero si lo tuyo no es la tecnolog\u00eda, existen tambi\u00e9n p\u00e1ginas m\u00e1s sencillas para ambientar con ruidos de fondo, como por ejemplo <a href=\"https:\/\/imissmycafe.com\/\">IMissMyCafe.com<\/a>, en la que tienes todos los sonidos de una cafeter\u00eda.<\/p>\n\n\n\n<p>Ya sea que est\u00e9s tratando de focalizarte mejor mientras estudias o simplemente quieras formar parte de una comunidad con otros estudiantes, estos sitios web te beneficiar\u00e1n. En todo caso, si est\u00e1s buscando otros m\u00e9todos para mejorar la organizaci\u00f3n de tu estudio, cuentas tambi\u00e9n con una gran variedad de opciones online, de las que te dejamos una selecci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.notion.so\/\">Notion.so<\/a>: organizador de tareas multiplataforma, que permite gestionar la planificaci\u00f3n de la vida laboral y personal.<\/li><li><a href=\"https:\/\/www.mybib.com\/\">MyBib<\/a>: ayuda a referenciar y citar con cualquier tipo de normas.<\/li><li><a href=\"https:\/\/www.forestapp.cc\/\">Forest<\/a>: ayuda a la desaparici\u00f3n de la procrastinaci\u00f3n mientras vas abonando un \u00e1rbol a medida que te mantienes concentrado.<\/li><li><a href=\"https:\/\/www.kadama.com\/\">Kadama<\/a>: proporciona tutor\u00eda, ayuda con tus deberes y a la preparaci\u00f3n de redacciones.&nbsp;<\/li><li><a href=\"https:\/\/www.reverso.net\/ortografia\/corrector-espanol\/?gclid=CjwKCAiAxvGfBhB-EiwAMPakqidnzLFMg-NKEQGUol6RLGo5FOzQfRohNHwwcAZuUr7eeqA8zgL6cxoCiKEQAvD_BwE\">Reverso.net<\/a>: herramienta de escritura que corrige la ortograf\u00eda, tipograf\u00eda, gram\u00e1tica y estilo de las redacciones.<\/li><li><a href=\"https:\/\/www.cofocus.one\/\">Cofocus.one<\/a>: agenda una videollamada con una persona aleatoria para estudiar al mismo tiempo.<\/li><\/ul>\n\n\n\n<p><strong>Saioa R. Erazo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La concentraci\u00f3n es uno de los factores m\u00e1s importantes en la vida de las personas, sobretodo cuando uno es estudiante, ya que debe buscarse los medios para adquirir esta habilidad.\u00a0 En este sentido, cada cual tiene diferentes formas o m\u00e9todos de concentraci\u00f3n seg\u00fan sus capacidades. Algunos se refugian en la soledad de sus habitaciones, sin [&hellip;]<\/p>\n","protected":false},"author":515,"featured_media":2325,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[55,53],"tags":[],"class_list":{"0":"post-2321","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-articulos-de-actualidad","8":"category-temas-de-interes","9":"entry"},"_links":{"self":[{"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/posts\/2321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/users\/515"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/comments?post=2321"}],"version-history":[{"count":7,"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/posts\/2321\/revisions"}],"predecessor-version":[{"id":2333,"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/posts\/2321\/revisions\/2333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/media\/2325"}],"wp:attachment":[{"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/media?parent=2321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/categories?post=2321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deusto.es\/viviendodeusto\/eu\/wp-json\/wp\/v2\/tags?post=2321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}